{"id":31379,"date":"2026-01-14T11:23:59","date_gmt":"2026-01-14T09:23:59","guid":{"rendered":"https:\/\/biblia.md\/?post_type=product&#038;p=31379"},"modified":"2026-01-14T11:26:40","modified_gmt":"2026-01-14T09:26:40","slug":"centralitatea-lui-cristos-prezentarea-expozitiva-a-epistolei-lui-pavel-catre-coloseni-vol-2","status":"publish","type":"product","link":"https:\/\/biblia.md\/en\/shop\/centralitatea-lui-cristos-prezentarea-expozitiva-a-epistolei-lui-pavel-catre-coloseni-vol-2\/","title":{"rendered":"Centralitatea lui Cristos &#8211; Prezentarea expozitiva a Epistolei lui Pavel catre Coloseni, Vol. 2"},"content":{"rendered":"<p>Autorul este interesat de detalii, atat de cele tehnice, cum ar fi interactiunea cu textul grecesc s.a., cat si de cele mai putin tehnice, precum latura aplicabila a textului biblic, insa acestea sunt prezentate cititorului numai in masura in care ele ajuta la elucidarea temelor centrale ale epistolei, astfel incat lucrarea sa ofere o lectura placuta si accesibila. In plus, abordarea expozitiva a Epistolei lui Pavel catre coloseni faciliteaza si interactiunea constanta cu elemente importante din hermeneutica biblica, teologia sistematica sau chiar din teologia istorica.<\/p>\n<p>De asemenea, un alt merit indubitabil al lucrarii de fata etse si interactiunea larga (mai ales in notele de subsol) cu literatura de specialitate, disponibila pe plan national si international, asa incat cititorul este ajutat nu numai sa beneficieze de roadele altor studii teologice de valoare, dar si sa discearna intre punctele de vedere prezentate. Departe insa de a ramane un tratat strict academic, lucrarea lui Bebe Ciausu abunda in ilustratii alese cu grija si mai ales in aplicatii practice si de actualitate, menite sa dea viata demersului teologic. Nu in ultimul rand, este cu adevarat remarcabil moduli n care autorul reuseste sa integreze resursele poeziei si imnologiei crestine (mai ales pe cele izvorate din contextul romanesc), asa incat lucrarea dobandeste si o incarcatura poetica si doxologica aparte.<\/p>\n<p><strong>Bebe Ciausu<\/strong>\u00a0este pastorul Bisericii Baptiste \u201eHarul\u201d din Ineu, Arad, si autorul lucrarilor: Chemare la caracter in vremuri de compromis, Romanta rascumpararii, Domnia lui Cristos in viata credinciosului, Voi canta doar despre Isus \u2013 Istorisiri despre compunerea imnurilor sacre (vol. I), scrisa impreuna cu sotia sa, Bianca, si Drumul spre casa.<\/p>","protected":false},"excerpt":{"rendered":"<p style=\"text-align: center\"><strong>Prezentare expozitiva a Epistolei lui Pavel catre Coloseni &#8211; vol 2<\/strong><\/p>\n<p>Este o bucurie deosebita sa constatam ca piata de carte crestina din Romania incepe sa includa si comentarii biblice de o excelenta calitate, realizate de autori romani, comentarii care, in mod inevitabil, au o tangenta mai directa cu nevoile si contextul teologic al bisericilor din Romania. Din aceasta categorie face parte si lucrarea de fata \u2013 o lucrare care se remarca prin cateva calitati deosebite. Asa cum subtitlul sau clarifica, ea este o \u201eprezentare expozitiva\u201d a textului biblic, aducand in centrul atentiei temele majore ale epistolei, cu un accent deosebit pe cuvintele, expresiile si frazele importante ale epistolei.<\/p>\n<p>&nbsp;<\/p>","protected":false},"featured_media":31383,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[377,392],"product_tag":[],"class_list":{"0":"post-31379","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-carti","7":"product_cat-comentarii-biblice","8":"product_author-bebe-ciausu","9":"product_genre-knigi-rom","11":"first","12":"instock","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Centralitatea lui Cristos - Prezentarea expozitiva a Epistolei lui Pavel catre Coloseni, Vol. 2 - Societatea Biblic\u0103 din Moldova<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/biblia.md\/en\/shop\/centralitatea-lui-cristos-prezentarea-expozitiva-a-epistolei-lui-pavel-catre-coloseni-vol-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Centralitatea lui Cristos - Prezentarea expozitiva a Epistolei lui Pavel catre Coloseni, Vol. 2 - Societatea Biblic\u0103 din Moldova\" \/>\n<meta property=\"og:description\" content=\"Prezentare expozitiva a Epistolei lui Pavel catre Coloseni - vol 2 Este o bucurie deosebita sa constatam ca piata de carte crestina din Romania incepe sa includa si comentarii biblice de o excelenta calitate, realizate de autori romani, comentarii care, in mod inevitabil, au o tangenta mai directa cu nevoile si contextul teologic al bisericilor din Romania. Din aceasta categorie face parte si lucrarea de fata \u2013 o lucrare care se remarca prin cateva calitati deosebite. Asa cum subtitlul sau clarifica, ea este o \u201eprezentare expozitiva\u201d a textului biblic, aducand in centrul atentiei temele majore ale epistolei, cu un accent deosebit pe cuvintele, expresiile si frazele importante ale epistolei.  &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/biblia.md\/en\/shop\/centralitatea-lui-cristos-prezentarea-expozitiva-a-epistolei-lui-pavel-catre-coloseni-vol-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Societatea Biblic\u0103 din Moldova\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SocietateaBiblicaMoldova\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-14T09:26:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/biblia.md\/wp-content\/uploads\/2026\/01\/0000002096.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/biblia.md\\\/shop\\\/centralitatea-lui-cristos-prezentarea-expozitiva-a-epistolei-lui-pavel-catre-coloseni-vol-2\\\/\",\"url\":\"https:\\\/\\\/biblia.md\\\/shop\\\/centralitatea-lui-cristos-prezentarea-expozitiva-a-epistolei-lui-pavel-catre-coloseni-vol-2\\\/\",\"name\":\"Centralitatea lui Cristos - Prezentarea expozitiva a Epistolei lui Pavel catre Coloseni, Vol. 2 - Societatea Biblic\u0103 din Moldova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biblia.md\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/biblia.md\\\/shop\\\/centralitatea-lui-cristos-prezentarea-expozitiva-a-epistolei-lui-pavel-catre-coloseni-vol-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/biblia.md\\\/shop\\\/centralitatea-lui-cristos-prezentarea-expozitiva-a-epistolei-lui-pavel-catre-coloseni-vol-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biblia.md\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/0000002096.jpg\",\"datePublished\":\"2026-01-14T09:23:59+00:00\",\"dateModified\":\"2026-01-14T09:26:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/biblia.md\\\/shop\\\/centralitatea-lui-cristos-prezentarea-expozitiva-a-epistolei-lui-pavel-catre-coloseni-vol-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/biblia.md\\\/shop\\\/centralitatea-lui-cristos-prezentarea-expozitiva-a-epistolei-lui-pavel-catre-coloseni-vol-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/biblia.md\\\/shop\\\/centralitatea-lui-cristos-prezentarea-expozitiva-a-epistolei-lui-pavel-catre-coloseni-vol-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/biblia.md\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/0000002096.jpg\",\"contentUrl\":\"https:\\\/\\\/biblia.md\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/0000002096.jpg\",\"width\":450,\"height\":670},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/biblia.md\\\/shop\\\/centralitatea-lui-cristos-prezentarea-expozitiva-a-epistolei-lui-pavel-catre-coloseni-vol-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\\\/\\\/biblia.md\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/biblia.md\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Centralitatea lui Cristos &#8211; Prezentarea expozitiva a Epistolei lui Pavel catre Coloseni, Vol. 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/biblia.md\\\/#website\",\"url\":\"https:\\\/\\\/biblia.md\\\/\",\"name\":\"Societatea Biblic\u0103 din Moldova\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/biblia.md\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/biblia.md\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/biblia.md\\\/#organization\",\"name\":\"Societatea Biblic\u0103 din Moldova\",\"url\":\"https:\\\/\\\/biblia.md\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/biblia.md\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/biblia.md\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/icon_site.jpg\",\"contentUrl\":\"https:\\\/\\\/biblia.md\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/icon_site.jpg\",\"width\":656,\"height\":656,\"caption\":\"Societatea Biblic\u0103 din Moldova\"},\"image\":{\"@id\":\"https:\\\/\\\/biblia.md\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SocietateaBiblicaMoldova\\\/\",\"https:\\\/\\\/www.instagram.com\\\/biblia.md\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Centralitatea lui Cristos - Prezentarea expozitiva a Epistolei lui Pavel catre Coloseni, Vol. 2 - Societatea Biblic\u0103 din Moldova","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/biblia.md\/en\/shop\/centralitatea-lui-cristos-prezentarea-expozitiva-a-epistolei-lui-pavel-catre-coloseni-vol-2\/","og_locale":"en_US","og_type":"article","og_title":"Centralitatea lui Cristos - Prezentarea expozitiva a Epistolei lui Pavel catre Coloseni, Vol. 2 - Societatea Biblic\u0103 din Moldova","og_description":"Prezentare expozitiva a Epistolei lui Pavel catre Coloseni - vol 2 Este o bucurie deosebita sa constatam ca piata de carte crestina din Romania incepe sa includa si comentarii biblice de o excelenta calitate, realizate de autori romani, comentarii care, in mod inevitabil, au o tangenta mai directa cu nevoile si contextul teologic al bisericilor din Romania. Din aceasta categorie face parte si lucrarea de fata \u2013 o lucrare care se remarca prin cateva calitati deosebite. Asa cum subtitlul sau clarifica, ea este o \u201eprezentare expozitiva\u201d a textului biblic, aducand in centrul atentiei temele majore ale epistolei, cu un accent deosebit pe cuvintele, expresiile si frazele importante ale epistolei.  &nbsp;","og_url":"https:\/\/biblia.md\/en\/shop\/centralitatea-lui-cristos-prezentarea-expozitiva-a-epistolei-lui-pavel-catre-coloseni-vol-2\/","og_site_name":"Societatea Biblic\u0103 din Moldova","article_publisher":"https:\/\/www.facebook.com\/SocietateaBiblicaMoldova\/","article_modified_time":"2026-01-14T09:26:40+00:00","og_image":[{"width":450,"height":670,"url":"https:\/\/biblia.md\/wp-content\/uploads\/2026\/01\/0000002096.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/biblia.md\/shop\/centralitatea-lui-cristos-prezentarea-expozitiva-a-epistolei-lui-pavel-catre-coloseni-vol-2\/","url":"https:\/\/biblia.md\/shop\/centralitatea-lui-cristos-prezentarea-expozitiva-a-epistolei-lui-pavel-catre-coloseni-vol-2\/","name":"Centralitatea lui Cristos - Prezentarea expozitiva a Epistolei lui Pavel catre Coloseni, Vol. 2 - Societatea Biblic\u0103 din Moldova","isPartOf":{"@id":"https:\/\/biblia.md\/#website"},"primaryImageOfPage":{"@id":"https:\/\/biblia.md\/shop\/centralitatea-lui-cristos-prezentarea-expozitiva-a-epistolei-lui-pavel-catre-coloseni-vol-2\/#primaryimage"},"image":{"@id":"https:\/\/biblia.md\/shop\/centralitatea-lui-cristos-prezentarea-expozitiva-a-epistolei-lui-pavel-catre-coloseni-vol-2\/#primaryimage"},"thumbnailUrl":"https:\/\/biblia.md\/wp-content\/uploads\/2026\/01\/0000002096.jpg","datePublished":"2026-01-14T09:23:59+00:00","dateModified":"2026-01-14T09:26:40+00:00","breadcrumb":{"@id":"https:\/\/biblia.md\/shop\/centralitatea-lui-cristos-prezentarea-expozitiva-a-epistolei-lui-pavel-catre-coloseni-vol-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/biblia.md\/shop\/centralitatea-lui-cristos-prezentarea-expozitiva-a-epistolei-lui-pavel-catre-coloseni-vol-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/biblia.md\/shop\/centralitatea-lui-cristos-prezentarea-expozitiva-a-epistolei-lui-pavel-catre-coloseni-vol-2\/#primaryimage","url":"https:\/\/biblia.md\/wp-content\/uploads\/2026\/01\/0000002096.jpg","contentUrl":"https:\/\/biblia.md\/wp-content\/uploads\/2026\/01\/0000002096.jpg","width":450,"height":670},{"@type":"BreadcrumbList","@id":"https:\/\/biblia.md\/shop\/centralitatea-lui-cristos-prezentarea-expozitiva-a-epistolei-lui-pavel-catre-coloseni-vol-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/biblia.md\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/biblia.md\/shop\/"},{"@type":"ListItem","position":3,"name":"Centralitatea lui Cristos &#8211; Prezentarea expozitiva a Epistolei lui Pavel catre Coloseni, Vol. 2"}]},{"@type":"WebSite","@id":"https:\/\/biblia.md\/#website","url":"https:\/\/biblia.md\/","name":"Societatea Biblic\u0103 din Moldova","description":"","publisher":{"@id":"https:\/\/biblia.md\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/biblia.md\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/biblia.md\/#organization","name":"Societatea Biblic\u0103 din Moldova","url":"https:\/\/biblia.md\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/biblia.md\/#\/schema\/logo\/image\/","url":"https:\/\/biblia.md\/wp-content\/uploads\/2026\/01\/icon_site.jpg","contentUrl":"https:\/\/biblia.md\/wp-content\/uploads\/2026\/01\/icon_site.jpg","width":656,"height":656,"caption":"Societatea Biblic\u0103 din Moldova"},"image":{"@id":"https:\/\/biblia.md\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SocietateaBiblicaMoldova\/","https:\/\/www.instagram.com\/biblia.md\/"]}]}},"_links":{"self":[{"href":"https:\/\/biblia.md\/en\/wp-json\/wp\/v2\/product\/31379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biblia.md\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/biblia.md\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/biblia.md\/en\/wp-json\/wp\/v2\/comments?post=31379"}],"version-history":[{"count":3,"href":"https:\/\/biblia.md\/en\/wp-json\/wp\/v2\/product\/31379\/revisions"}],"predecessor-version":[{"id":31388,"href":"https:\/\/biblia.md\/en\/wp-json\/wp\/v2\/product\/31379\/revisions\/31388"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/biblia.md\/en\/wp-json\/wp\/v2\/media\/31383"}],"wp:attachment":[{"href":"https:\/\/biblia.md\/en\/wp-json\/wp\/v2\/media?parent=31379"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/biblia.md\/en\/wp-json\/wp\/v2\/product_brand?post=31379"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/biblia.md\/en\/wp-json\/wp\/v2\/product_cat?post=31379"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/biblia.md\/en\/wp-json\/wp\/v2\/product_tag?post=31379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}